{"text_format":"3","workbook":"xlsx","n_sheets":8,"sheets":["企業様へ","求人票(表)","求人票（記入例）","確認事項①(閲覧のみ)","確認事項②(閲覧のみ)","予備自衛官制度の概要(閲覧のみ)","求人票(裏)","宮城センター用"],"not_rendered":{"images":3,"macros":1,"external_links":9,"defined_names":446,"comments":1},"read":"whole","date_system":"1900"}

{"sheet":"企業様へ","index":0,"n_rows":2,"n_cols":2,"rows_kept":2,"merged":[[1,1,9,1]]}
[]
[null,"退職自衛官の求人をお考えの企業　様\n\n  新たな再就職規制に係る改正自衛隊法が平成２７年１０月１日から施行\nされたことに伴い、再就職結果の公表が義務付けられるとともに、防衛省\nにおける自主規制を受けて、紹介を行う日から遡って２年以内に、役員等\nが贈賄を行うなど刑法に違反する行為を行った営利企業等については、\n退職自衛官を紹介できないこととなりました。併せて、「個人情報の取扱\nい」及び「反社会的勢力の排除」に関する事項につきましても、確認でき\nない場合には退職自衛官を紹介できないこととなっております。\n\n　また、平成２９年４月１日から（即応）予備自衛官希望者の受け入れに\n関する検討の可能性について記入いただくこととなりました。\nこれは、国の施策である予備自衛官制度についてご理解・ご協力を得る\nきっかけとしたく設けたものです。\n　尚、当該欄の記入の有無により登録・紹介等の取扱が異なることはご\nざいません。ご検討を宜しくお願い申し上げます。\n\n　各企業様におかれましては、上記内容につきましてご理解頂き、今後\nとも、退職自衛官の再就職に関しまして、ご理解、ご協力を賜りますよう、\n宜しくお願い申し上げます。\n\n                           ２０２３年４月１日\n\n                                          退職自衛官仙台無料職業紹介所\n　　                                                            所長　佐藤　芳一\n"]

{"sheet":"求人票(表)","index":1,"n_rows":172,"n_cols":231,"rows_kept":172,"merged":[[4,0,9,5],[4,13,6,25],[4,28,6,65],[4,68,5,92],[4,93,5,203],[4,205,5,231],[5,10,5,11],[6,68,9,92],[6,116,7,124],[6,138,7,148],[6,160,7,174],[6,182,7,196],[6,205,11,208],[7,13,9,25],[7,28,9,65],[7,94,8,98],[7,99,8,103],[7,104,8,108],[7,109,8,113],[7,210,10,230],[8,10,8,11],[8,116,9,122],[8,123,9,124],[8,125,9,137],[8,138,9,159],[8,160,9,181],[8,182,9,203],[10,0,103,0],[10,1,103,1],[10,2,103,2],[10,3,103,3],[10,4,103,4],[10,5,103,5],[10,6,103,6],[10,7,10,171],[11,7,12,20],[11,21,12,83],[11,84,33,88],[11,89,27,92],[11,116,21,119],[11,149,24,152],[12,95,13,98],[12,99,13,101],[12,104,13,107],[12,108,13,113],[12,122,13,125],[12,126,13,128],[12,129,13,130],[12,131,13,133],[12,134,13,135],[12,136,13,137],[12,138,13,140],[12,141,13,142],[12,143,13,145],[12,146,13,147],[12,154,12,155],[12,157,12,201],[12,205,22,208],[13,7,16,20],[13,21,16,83],[13,188,13,192],[13,193,13,200],[13,210,16,230],[14,154,14,155],[15,95,16,98],[15,99,16,101],[15,104,16,107],[15,108,16,114],[15,122,16,125],[15,126,16,128],[15,129,16,130],[15,131,16,133],[15,134,16,135],[15,136,16,137],[15,138,16,140],[15,141,16,142],[15,143,16,145],[15,146,16,147],[15,178,15,180],[15,184,15,186],[15,190,15,192],[17,7,19,20],[17,21,19,83],[17,156,17,157],[17,165,17,166],[17,175,17,176],[17,192,17,193],[18,122,19,125],[18,126,19,128],[18,129,19,130],[18,131,19,133],[18,134,19,135],[18,136,19,137],[18,138,19,140],[18,141,19,142],[18,143,19,145],[18,146,19,147],[19,157,19,200],[19,210,21,215],[19,216,21,217],[19,218,21,220],[19,221,21,222],[19,223,21,225],[19,226,21,227],[19,228,21,230],[20,7,26,20],[20,21,21,23],[20,24,21,41],[20,169,20,170],[20,178,20,179],[21,122,22,125],[21,126,22,128],[21,129,22,130],[21,131,22,133],[21,134,22,135],[21,136,22,137],[21,138,22,140],[21,141,22,142],[21,143,22,145],[21,146,22,147],[21,172,21,200],[22,22,24,82],[22,104,22,109],[22,116,22,119],[23,117,23,118],[23,168,23,169],[23,176,23,177],[23,205,27,208],[23,209,27,231],[24,93,24,115],[24,121,24,146],[25,22,26,49],[25,50,26,52],[25,53,26,60],[25,61,26,62],[25,63,26,70],[25,71,26,72],[25,73,26,83],[25,116,25,119],[25,121,27,148],[25,149,27,152],[25,194,30,196],[25,198,28,202],[26,103,26,112],[26,117,26,118],[26,154,26,155],[26,173,26,177],[26,187,26,188],[27,7,31,20],[27,21,28,27],[27,44,28,49],[27,50,28,83],[28,89,30,100],[28,174,30,183],[28,205,35,208],[28,209,32,231],[29,22,31,49],[29,50,31,52],[29,53,31,60],[29,61,31,62],[29,63,31,70],[29,71,31,72],[29,73,31,83],[29,102,29,103],[29,109,29,110],[29,116,29,117],[29,123,29,124],[29,125,29,143],[29,145,29,146],[29,156,29,170],[29,171,29,172],[29,184,29,190],[29,200,30,202],[31,89,33,100],[31,174,33,183],[32,7,50,10],[32,11,35,20],[32,21,35,83],[32,102,32,103],[32,111,32,112],[32,120,32,121],[32,126,32,129],[32,136,32,137],[32,148,32,162],[32,167,32,168],[32,185,32,198],[32,199,32,202],[33,209,35,211],[33,212,35,214],[33,215,35,229],[33,230,35,231],[34,84,71,88],[34,89,36,100],[35,102,35,103],[35,112,35,113],[35,122,35,123],[35,135,35,136],[35,157,35,158],[35,166,35,168],[35,169,35,199],[36,11,44,20],[36,24,37,24],[36,25,38,31],[36,36,38,46],[36,62,38,63],[36,64,44,69],[36,70,40,75],[36,76,40,79],[36,80,40,83],[37,22,37,23],[37,33,37,34],[37,51,37,59],[37,89,39,100],[37,102,39,113],[37,116,39,120],[37,127,39,129],[37,133,39,141],[37,151,39,153],[37,155,39,162],[37,165,39,169],[37,182,39,190],[37,200,39,202],[37,205,38,231],[38,114,38,115],[38,121,38,126],[38,131,38,132],[38,142,38,150],[38,163,38,164],[38,170,38,175],[38,180,38,181],[38,191,38,199],[39,24,40,24],[39,25,41,35],[39,40,41,46],[39,52,41,60],[39,62,41,63],[39,205,92,231],[40,22,40,23],[40,37,40,38],[40,49,40,50],[40,89,65,91],[40,92,54,100],[40,101,40,127],[40,128,40,160],[40,161,40,186],[41,70,44,75],[41,76,44,79],[41,80,44,83],[41,101,42,124],[41,125,42,129],[41,130,42,153],[41,154,42,158],[41,161,42,177],[41,178,42,181],[41,182,42,198],[41,199,42,202],[42,25,44,63],[43,22,43,23],[44,101,45,115],[44,116,45,120],[44,121,45,133],[44,134,45,138],[44,139,45,151],[44,152,45,154],[44,156,45,166],[44,167,45,171],[44,172,45,182],[44,183,45,187],[44,188,45,198],[44,199,45,201],[45,11,46,20],[45,21,46,83],[46,101,47,115],[46,116,47,120],[46,121,47,133],[46,134,47,138],[46,139,47,151],[46,152,47,154],[46,156,47,166],[46,167,47,171],[46,172,47,182],[46,183,47,187],[46,188,47,198],[46,199,47,202],[48,101,49,115],[48,116,49,120],[48,121,49,133],[48,134,49,138],[48,139,49,151],[48,152,49,154],[48,156,49,166],[48,167,49,171],[48,172,49,182],[48,183,49,187],[48,188,49,198],[48,199,49,202],[49,11,50,83],[50,101,51,115],[50,116,51,122],[50,123,51,130],[50,131,51,143],[50,144,51,149],[50,150,51,162],[50,163,51,168],[51,7,78,10],[51,11,63,14],[51,26,51,27],[52,17,54,81],[52,101,54,107],[52,108,54,130],[52,131,54,136],[52,137,54,163],[52,164,54,167],[52,175,54,203],[55,18,55,31],[55,38,55,51],[55,54,55,59],[55,64,55,67],[55,68,55,72],[55,73,55,77],[55,92,65,100],[55,101,56,124],[55,125,56,129],[55,130,56,147],[55,148,56,150],[55,151,56,153],[55,154,56,171],[55,172,56,174],[55,175,56,184],[55,185,56,199],[55,200,56,203],[56,29,58,75],[57,77,57,78],[57,101,58,124],[57,125,58,129],[57,130,58,147],[57,148,58,150],[57,151,58,153],[57,154,58,171],[57,172,58,174],[57,175,58,184],[57,185,58,199],[57,200,58,203],[59,15,63,23],[59,101,60,124],[59,125,60,129],[59,130,60,147],[59,148,60,150],[59,151,60,153],[59,154,60,171],[59,172,60,174],[59,175,60,184],[59,185,60,199],[59,200,60,203],[60,26,60,27],[60,36,60,37],[60,44,60,45],[60,59,60,60],[60,70,60,81],[60,82,60,83],[61,101,62,118],[61,119,62,125],[61,126,62,138],[61,139,62,151],[61,152,62,157],[61,158,62,170],[61,171,62,176],[62,24,63,31],[62,33,63,82],[63,101,65,109],[64,11,78,14],[64,111,64,112],[64,124,64,138],[64,149,64,150],[64,158,64,172],[64,192,64,193],[65,16,75,82],[66,89,68,100],[66,101,68,106],[67,111,67,112],[67,147,67,159],[67,160,67,162],[67,166,67,179],[67,192,67,193],[69,89,71,100],[69,101,71,106],[70,111,70,112],[70,134,70,139],[70,148,70,155],[70,165,70,175],[70,192,70,193],[72,84,83,88],[72,89,74,100],[73,102,73,103],[73,104,73,108],[73,111,73,112],[73,113,73,117],[73,120,73,121],[73,122,73,126],[73,129,73,130],[73,131,73,140],[73,142,73,143],[73,144,73,155],[73,157,73,158],[73,159,73,164],[75,89,77,100],[75,150,77,161],[76,29,78,75],[76,109,76,110],[76,120,76,125],[76,142,76,143],[76,164,76,165],[76,175,76,176],[77,77,77,78],[78,89,80,100],[78,150,80,161],[79,7,86,10],[79,11,80,75],[79,103,79,104],[79,110,79,114],[79,122,79,123],[79,164,79,165],[79,172,79,176],[79,192,79,193],[81,11,84,82],[81,89,83,100],[81,101,83,112],[81,150,83,161],[82,114,82,115],[82,121,82,122],[82,123,82,129],[82,131,82,132],[82,133,82,139],[82,142,82,143],[82,164,82,165],[82,171,82,172],[82,173,82,179],[82,181,82,182],[82,183,82,189],[82,192,82,193],[84,84,94,88],[85,11,86,20],[85,21,86,83],[85,89,85,105],[85,106,85,113],[85,114,85,116],[85,117,85,121],[85,122,85,124],[85,125,85,129],[85,130,85,132],[85,135,85,182],[87,7,102,10],[87,11,90,20],[87,22,90,62],[87,64,90,69],[87,71,88,75],[87,89,87,125],[87,127,87,128],[87,144,87,145],[87,153,87,193],[89,71,90,79],[89,89,89,105],[89,106,89,107],[89,116,89,117],[89,118,89,122],[89,123,89,128],[89,129,89,133],[89,140,89,150],[89,152,89,153],[89,161,89,162],[89,170,89,172],[89,173,89,193],[91,11,93,20],[91,21,92,35],[91,36,92,39],[91,40,94,46],[91,64,94,69],[91,89,91,105],[91,106,91,107],[91,108,91,114],[91,116,91,117],[91,118,91,127],[91,130,91,131],[91,132,91,141],[91,144,91,145],[91,146,91,153],[91,155,91,156],[91,158,91,193],[92,48,93,60],[92,61,93,62],[92,74,93,75],[92,81,93,82],[93,32,93,35],[93,36,93,39],[93,71,93,72],[93,78,93,79],[93,89,93,98],[93,100,94,202],[93,205,94,231],[94,11,94,20],[94,21,94,23],[94,24,94,35],[95,11,96,82],[95,84,98,88],[95,89,96,128],[95,131,96,180],[95,205,98,211],[95,212,98,218],[95,219,98,225],[95,226,98,231],[97,12,101,82],[97,91,98,116],[97,117,97,118],[97,127,98,142],[97,144,97,145],[97,146,98,150],[97,155,97,156],[97,157,98,167],[99,84,100,198],[99,205,100,231],[101,94,101,95],[101,119,101,120],[101,205,102,231]]}
[]
[]
[]
[]
[{"$nulls":13},"定年制",{"$nulls":14},"求　　人　　票",{"$nulls":39},"         紹　介　期　限",{"$nulls":24},"紹　　介　　所　　専　　用　　整　　理　　欄",{"$nulls":111},"受付機関整理欄"]
[]
[{"$nulls":116},"受理番号",{"$nulls":21},"受理年月日",{"$nulls":21},"産業分類番号",{"$nulls":21},"職業分類番号",{"$nulls":22},"番号"]
[{"$nulls":13},"任期制",{"$nulls":14},"退職自衛官仙台無料職業紹介所",{"$nulls":65},"A",{"$nulls":4},"B",{"$nulls":4},"C",{"$nulls":4},"D"]
[{"$nulls":10},"　",{"$nulls":105},{"$f":"IF(K6=\"■\",\"T\",IF(K9=\"\",\"\",\"N\"))","v":"N"},{"$nulls":6},"-"]
[]
["［個人情報苦情及び相談窓口］一般財団法人自衛隊援護協会　事務局総務課（03‐5227‐5400）","　ては、左記にご連絡ください。遅滞なく回答いたします。  ","　はありません。なお、所定の項目にご記入いただけない場合には、適切な対応ができない場合があります。開示対象個人情報につい","　場合があります。求職者への提供、本人の同意がある場合又は法令に基づく場合を除き、取得した個人情報を第三者に提供すること","　ご記入いただいた個人情報は、求人者に適切な人材を紹介するために利用いたします。上記利用目的達成のため一部業務を委託する","［個人情報のお取扱いについて］個人情報保護管理者 事務局長","（記入上の注意）太線枠内を記入してください。"]
[{"$nulls":7},"ふりがな",{"$nulls":76},"就　業　時　間",{"$nulls":4},"就業時間",{"$nulls":26},"交替制",{"$nulls":32},"雇用期間"]
[{"$nulls":99},"時",{"$nulls":8},"分から",{"$nulls":13},"①",{"$nulls":6},"時",{"$nulls":4},"分",null,"～",{"$nulls":4},"時",{"$nulls":4},"分",{"$nulls":10},"雇用期間の定め 無",{"$nulls":47},"機　関　名"]
[{"$nulls":7},"事業所名",{"$nulls":169},"雇用期間",{"$nulls":15},"ケ月間"]
[{"$nulls":157},"雇用期間の定め 有",{"$nulls":28},"又は"]
[{"$nulls":99},"時",{"$nulls":8},"分まで",{"$nulls":13},"②",{"$nulls":6},"時",{"$nulls":4},"分",null,"～",{"$nulls":4},"時",{"$nulls":4},"分",{"$nulls":34},"年",{"$nulls":5},"月",{"$nulls":5},"日まで"]
[{"$nulls":154},"・更新の有無"]
[{"$nulls":7},"代表者\n氏　　名",{"$nulls":151},"有",{"$nulls":3},"（",{"$nulls":3},"条件有",{"$nulls":9},"原則更新",{"$nulls":10},"）",{"$nulls":6},"無"]
[{"$nulls":122},"③",{"$nulls":6},"時",{"$nulls":4},"分",null,"～",{"$nulls":4},"時",{"$nulls":4},"分",{"$nulls":7},"・更新の条件："]
[{"$nulls":154},"（",{"$nulls":47},"）",{"$nulls":7},"地本",{"$nulls":5},"●",null,"陸",null,null,"●",null,"空",null,null,"●",null,"海"]
[{"$nulls":7},"所在地",{"$nulls":13},"〒",{"$nulls":71},"※シフト制の場合　　　　　　　",{"$nulls":60},"・更新の上限：",{"$nulls":17},"有",{"$nulls":8},"無"]
[{"$nulls":122},"④",{"$nulls":6},"時",{"$nulls":4},"分",null,"～",{"$nulls":4},"時",{"$nulls":4},"分",{"$nulls":9},"（具体的な上限：",{"$nulls":45},"）"]
[{"$nulls":93},"(",null,"この間の",{"$nulls":14},"時間",{"$nulls":3},")",null,"有",{"$nulls":37},"・雇用期間経過後に正社員（期間の定め無）登用",{"$nulls":41},"）"]
[{"$nulls":156},"の可能性",{"$nulls":14},"有",{"$nulls":7},"無",{"$nulls":25},"年月日"]
[{"$nulls":93},"※変形労働時間制の場合",{"$nulls":27},"特記事項"]
[{"$nulls":50},"☎",{"$nulls":10},"（",{"$nulls":9},"）",{"$nulls":44},"無",{"$nulls":32},"時間外",{"$nulls":44},"休憩時間",null,null,"\n\n\n分"]
[{"$nulls":93},"(",null,"単位等：",{"$nulls":17},")",{"$nulls":43},"有",null,null,"（月平均時間",{"$nulls":23},"時間）",{"$nulls":5},"無"]
[{"$nulls":7},"採用事務\n担　当　者",{"$nulls":13},"部課名",{"$nulls":22},"氏名",{"$nulls":136},"　",{"$nulls":5},"　"]
[{"$nulls":89},"休日",{"$nulls":57},"　",{"$nulls":26},"年間休日数",{"$nulls":30},"担当者"]
[{"$nulls":50},"☎",{"$nulls":10},"（",{"$nulls":9},"）",{"$nulls":32},"土曜",{"$nulls":6},"日曜",{"$nulls":6},"祝日",{"$nulls":6},"会社カレンダーによる",{"$nulls":21},"その他（",{"$nulls":23},"）",{"$nulls":19},"日",{"$nulls":8},"分"]
[]
[{"$nulls":89},"週休２日制",{"$nulls":84},"年間所定\n労働時間"]
[{"$nulls":7},"職種・年齢等",{"$nulls":3},"職　　種",{"$nulls":93},"完全",{"$nulls":8},"隔週",{"$nulls":8},"月",{"$nulls":6},"回休",{"$nulls":8},"その他",{"$nulls":6},"(",{"$nulls":17},")",{"$nulls":5},"無",{"$nulls":14},{"$f":"IF(OR(CR13=\"\",DA13=\"\",CR16=\"\",DA16=\"\",GC30=\"\"),\"\",ROUND(IF(DA23=\"\",(HOUR(TIME(VALUE(CR16),VALUE(DA16),0)-TIME(VALUE(CR13),VALUE(DA13),0)-TIME(0,GQ26,0))+MINUTE(TIME(VALUE(CR16),VALUE(DA16),0)-TIME(VALUE(CR13),VALUE(DA13),0)-TIME(0,GQ26,0))/60),DA23)*(365-GC30),0))","v":""},{"$nulls":13},"時間"]
[{"$nulls":102},"　",{"$nulls":6},"　",{"$nulls":6},"　",{"$nulls":13},"　",{"$nulls":6},"　",{"$nulls":71},"（",null,null,"(",{"$nulls":17},"）"]
[{"$nulls":84},"賃金",{"$nulls":4},"賃金形態"]
[{"$nulls":104},"年俸制",{"$nulls":9},"月給制",{"$nulls":9},"日給制",{"$nulls":12},"時間給制",{"$nulls":21},"その他",{"$nulls":6},"（",{"$nulls":34},"）"]
[{"$nulls":11},"雇用形態",{"$nulls":13},"正社員",{"$nulls":10},"正社員以外",{"$nulls":27},"採用　人員　",{"$nulls":5},"通勤",{"$nulls":9},"人",{"$nulls":21},"　"]
[{"$nulls":48},"（",{"$nulls":11},"）",{"$nulls":28},"賃金支払",{"$nulls":12},"賃金締切日",{"$nulls":13},"毎月",{"$nulls":5},"　",{"$nulls":4},"日",{"$nulls":5},"その他（",{"$nulls":13},"　",{"$nulls":3},"）",{"$nulls":3},"支払日",{"$nulls":9},"毎月",{"$nulls":16},"その他（",{"$nulls":13},"　",{"$nulls":3},"）",{"$nulls":4},"その他（求人に関する特記事項)"]
[{"$nulls":176},"日"]
[{"$nulls":25},"派遣・請負でない",{"$nulls":14},"有期雇用派遣",{"$nulls":11},"無期雇用派遣"]
[{"$nulls":89},"毎月の賃金（税込み）",null,null,"定期的に支払われる賃金",{"$nulls":8},"ａ基本給＜月額で表記＞",{"$nulls":59},"※年俸制の場合の年間給与額"]
[{"$nulls":70},"住込",{"$nulls":9},"人",{"$nulls":44},"円～",{"$nulls":28},"円",{"$nulls":23},"円～",{"$nulls":20},"円"]
[{"$nulls":25},"請負（他の事業所で就業する仕事の場合）"]
[{"$nulls":101},"ｂ手当"]
[{"$nulls":116},"手当",{"$nulls":17},"円～",{"$nulls":17},"円",{"$nulls":14},"手当",{"$nulls":15},"円～",{"$nulls":15},"円"]
[{"$nulls":11},"役 職 名"]
[{"$nulls":116},"手当",{"$nulls":17},"円～",{"$nulls":17},"円",{"$nulls":14},"手当",{"$nulls":15},"円～",{"$nulls":15},"円"]
[{"$nulls":11},"(労働施策総合推進法　施行規則第１条の３第１項に該当）"]
[{"$nulls":11},"(定年以外の年齢制限がある場合の理由）",{"$nulls":104},"手当",{"$nulls":17},"円～",{"$nulls":17},"円",{"$nulls":14},"手当",{"$nulls":15},"円～",{"$nulls":15},"円"]
[]
[{"$nulls":101},"（固定残業代：",{"$nulls":21},"時間分）",{"$nulls":20},"円～",{"$nulls":18},"円"]
[{"$nulls":7},"職務内容",{"$nulls":3},"就業場所",{"$nulls":3},"（雇入れ直後）",{"$nulls":14},"事業所に同じ。　同じでない場合は住所を記入。"]
[{"$nulls":101},"ａ+ｂ",{"$nulls":6},{"$f":"SUM(CX42,DR45:ED50,FQ45:GA50,EB51)","v":0},{"$nulls":22},"円～",{"$nulls":5},{"$f":"SUM(EA42,EJ45:EV50,GG45:GQ50,EU51)","v":0},{"$nulls":26},"円",{"$nulls":10},"※固定残業代を採用する場合、固定残業時間を超える時間外労働分は追加で支給"]
[]
[]
[{"$nulls":15},"（",{"$nulls":16},"）線（",{"$nulls":19},"）",null,"駅",{"$nulls":5},"から",{"$nulls":3},"徒歩",{"$nulls":3},"で（",{"$nulls":9},"）分",{"$nulls":13},"個人の状態に応じて支払われる賃金",{"$nulls":32},"手当",{"$nulls":22},"円",null,null,"～",{"$nulls":20},"円",null,null,"家族手当",{"$nulls":24},"円"]
[{"$nulls":15},"（変更の範囲）"]
[{"$nulls":79},"無",{"$nulls":45},"手当",{"$nulls":22},"円",null,null,"～",{"$nulls":20},"円",null,null,"配偶者",{"$nulls":24},"円"]
[]
[{"$nulls":15},"屋内の受動喫煙対策",{"$nulls":109},"手当",{"$nulls":22},"円",null,null,"～",{"$nulls":20},"円",null,null,"子供",{"$nulls":24},"円"]
[{"$nulls":28},"あり",{"$nulls":4},"（",{"$nulls":4},"禁煙",{"$nulls":7},"喫煙室あり",{"$nulls":9},"）",{"$nulls":4},"その他（",{"$nulls":20},"）"]
[{"$nulls":101},"時間外手当（月平均",{"$nulls":24},"時間相当分）",{"$nulls":25},"円～",{"$nulls":18},"円"]
[{"$nulls":24},"特記事項："]
[{"$nulls":101},"通勤手当"]
[{"$nulls":11},"仕事の内容",{"$nulls":3},"（雇入れ直後）",{"$nulls":97},"実費（最高",{"$nulls":25},"円まで）",{"$nulls":11},"定額（",{"$nulls":21},"円）",{"$nulls":18},"　",null,"無"]
[{"$nulls":111},"　",{"$nulls":37},"　"]
[{"$nulls":89},"昇給",{"$nulls":11},"制度"]
[{"$nulls":113},"有",{"$nulls":4},"ベースアップ込みの前年度実績",{"$nulls":41},"円",null,null,"～",{"$nulls":16},{"$f":"FE68","v":"円"},{"$nulls":13},"無"]
[]
[{"$nulls":89},"賞与",{"$nulls":11},"制度"]
[{"$nulls":113},"有",{"$nulls":4},"前年度実績 年",{"$nulls":21},"回",{"$nulls":3},"（",{"$nulls":11},"月分又は",{"$nulls":19},"万円）",{"$nulls":17},"無"]
[]
[{"$nulls":84},"福利厚生等",{"$nulls":4},"加入保険"]
[{"$nulls":104},"雇用",{"$nulls":8},"労災",{"$nulls":8},"健康",{"$nulls":8},"厚生年金",{"$nulls":12},"退職金共済",{"$nulls":14},"財形"]
[{"$nulls":102},"　",{"$nulls":17},"　",{"$nulls":9},"　",{"$nulls":12},"　",{"$nulls":16},"　"]
[{"$nulls":89},"退職金制度",{"$nulls":60},"通　学"]
[{"$nulls":15},"（変更の範囲）",{"$nulls":86},"制度",{"$nulls":8},"有（最低",{"$nulls":14},"年勤続）",{"$nulls":17},"無",{"$nulls":21},"可",{"$nulls":10},"否"]
[{"$nulls":79},"無",{"$nulls":28},"　",{"$nulls":30},"　",{"$nulls":36},"　"]
[{"$nulls":89},"定年制",{"$nulls":18},"　",{"$nulls":41},"再雇用又は勤務延長　",{"$nulls":17},"　",{"$nulls":15},"　"]
[{"$nulls":7},"必須技能等",{"$nulls":3},"必要な経験（年数）・技能・知識・免許資格",{"$nulls":93},"有（",{"$nulls":9},"歳）",{"$nulls":8},"無",{"$nulls":41},"有（",{"$nulls":11},"歳）",{"$nulls":15},"無"]
[]
[{"$nulls":89},"住宅",{"$nulls":11},"単身者用",{"$nulls":48},"世帯用"]
[{"$nulls":116},"有（",{"$nulls":6},"入居可",{"$nulls":9},"不可）",{"$nulls":10},"無",{"$nulls":21},"有（",{"$nulls":6},"入居可",{"$nulls":9},"不可）",{"$nulls":10},"無"]
[]
[{"$nulls":84},"備　　考"]
[{"$nulls":11},"学　　歴",{"$nulls":77},"・採用希望期限",{"$nulls":24},"年",{"$nulls":7},"月",{"$nulls":7},"日",{"$nulls":4},"指定のない場合の有効期間は３か月間です。"]
[]
[{"$nulls":7},"事業所の概要",{"$nulls":3},"主たる　生産品目　　事業内容",{"$nulls":52},"創立設立",{"$nulls":6},"西暦",{"$nulls":17},"・採用を希望する者の自衛隊時の階級",{"$nulls":39},"特になし",{"$nulls":16},"あり（",{"$nulls":47},"）"]
[{"$nulls":127},"　"]
[{"$nulls":89},"・試用期間",{"$nulls":18},"無",{"$nulls":9},"有（",{"$nulls":10},"月）",{"$nulls":10},"労働条件",{"$nulls":13},"同じ",{"$nulls":8},"異なる",{"$nulls":6},"（",{"$nulls":23},"）"]
[{"$nulls":80},"年"]
[{"$nulls":11},"従業員数",{"$nulls":24},"人",{"$nulls":3},"資本金",{"$nulls":23},"労働\n組合",{"$nulls":24},"・選考方法",{"$nulls":18},"面　接",{"$nulls":9},"書類選考",{"$nulls":13},"筆記試験",{"$nulls":13},"その他",{"$nulls":7},"（","（",{"$nulls":38},"）"]
[{"$nulls":61},"円",{"$nulls":12},"有",{"$nulls":6},"無"]
[{"$nulls":21},"（うち女子",{"$nulls":14},"人）",{"$nulls":52},"・その他",{"$nulls":115},"【連携企業情報】"]
[{"$nulls":11},"全従業員数",{"$nulls":24},"人"]
[{"$nulls":11},"（年商額など最近の業績及び会社のPRなど）",{"$nulls":72},"確認事項",{"$nulls":4},"・退職自衛官の採用に関する確認事項",{"$nulls":41},"（確認した場合は□を黒塗りして下さい。）"]
[]
[{"$nulls":91},"○第１項～第４項、第６項",{"$nulls":35},"○第5項に該当（",{"$nulls":18},"する",{"$nulls":10},"しない　）"]
[]
[{"$nulls":84},"予備自衛官等希望者の採用（採用をご検討いただける場合は□を黒塗りして下さい。両方を選択いただくことも可能です。）",{"$nulls":120},"【求職者援護開始年月日】"]
[]
[{"$nulls":96},"即応予備自衛官",{"$nulls":24},"予備自衛官"]
[]
[]
[{"$nulls":83},"　　　　　　"]
[]
[{"$nulls":83},"　"]
{"$rows_empty":63}
[null,"■",null,null,2,2]
[{"$nulls":4},2,2]

{"sheet":"求人票（記入例）","index":2,"n_rows":169,"n_cols":220,"rows_kept":169,"merged":[[1,4,6,9],[1,17,3,29],[1,32,3,69],[1,72,2,96],[1,97,2,207],[1,209,2,235],[2,14,2,15],[3,72,6,96],[3,97,6,119],[3,120,6,141],[3,142,6,163],[3,164,6,185],[3,186,6,207],[3,209,8,212],[4,17,6,29],[4,32,6,69],[4,214,7,234],[5,14,5,15],[7,4,100,4],[7,5,100,5],[7,6,100,6],[7,7,100,7],[7,8,100,8],[7,9,100,9],[7,10,100,10],[7,11,7,175],[8,11,9,24],[8,25,9,87],[8,88,30,92],[8,93,24,96],[8,120,18,123],[8,153,21,156],[9,99,10,102],[9,103,10,105],[9,108,10,111],[9,112,10,117],[9,126,10,129],[9,130,10,132],[9,133,10,134],[9,135,10,137],[9,138,10,139],[9,140,10,141],[9,142,10,144],[9,145,10,146],[9,147,10,149],[9,150,10,151],[9,158,9,159],[9,161,9,205],[9,209,19,212],[10,11,13,24],[10,25,13,87],[10,190,10,196],[10,197,10,204],[10,214,13,234],[11,158,11,159],[12,99,13,102],[12,103,13,105],[12,108,13,111],[12,112,13,118],[12,126,13,129],[12,130,13,132],[12,133,13,134],[12,135,13,137],[12,138,13,139],[12,140,13,141],[12,142,13,144],[12,145,13,146],[12,147,13,149],[12,150,13,151],[12,182,12,184],[12,188,12,190],[12,194,12,196],[14,11,16,24],[14,25,16,87],[14,160,14,161],[14,169,14,170],[14,179,14,180],[14,196,14,197],[15,126,16,129],[15,130,16,132],[15,133,16,134],[15,135,16,137],[15,138,16,139],[15,140,16,141],[15,142,16,144],[15,145,16,146],[15,147,16,149],[15,150,16,151],[15,213,19,235],[16,161,16,204],[17,11,23,24],[17,25,18,27],[17,28,18,34],[17,35,18,37],[17,38,18,45],[17,173,17,174],[17,182,17,183],[18,126,19,129],[18,130,19,132],[18,133,19,134],[18,135,19,137],[18,138,19,139],[18,140,19,141],[18,142,19,144],[18,145,19,146],[18,147,19,149],[18,150,19,151],[18,176,18,204],[19,26,21,86],[19,108,19,111],[19,120,19,123],[20,121,20,122],[20,172,20,173],[20,180,20,181],[20,209,24,212],[20,213,24,235],[21,97,21,119],[21,125,21,150],[22,26,23,53],[22,54,23,56],[22,57,23,64],[22,65,23,66],[22,67,23,74],[22,75,23,76],[22,77,23,87],[22,120,22,123],[22,125,24,152],[22,153,24,161],[22,198,27,200],[22,202,25,206],[23,107,23,116],[23,121,23,122],[23,163,23,164],[23,182,23,184],[23,191,23,192],[24,11,28,24],[24,25,25,31],[24,32,28,47],[24,48,25,53],[24,54,25,87],[25,93,27,104],[25,178,27,187],[25,209,32,212],[25,213,29,235],[26,54,28,56],[26,57,28,64],[26,65,28,66],[26,67,28,74],[26,75,28,76],[26,77,28,87],[26,106,26,107],[26,113,26,114],[26,120,26,121],[26,127,26,128],[26,129,26,147],[26,149,26,150],[26,162,26,174],[26,175,26,176],[26,188,26,194],[26,204,27,206],[28,93,30,104],[28,180,30,191],[29,11,48,14],[29,15,33,17],[29,106,29,107],[29,115,29,116],[29,124,29,125],[29,130,29,133],[29,140,29,141],[29,147,29,148],[29,160,29,175],[29,192,29,202],[29,203,29,206],[30,19,33,86],[30,213,32,215],[30,216,32,218],[30,219,32,235],[31,88,68,92],[31,93,33,104],[32,106,32,107],[32,116,32,117],[32,126,32,127],[32,139,32,140],[32,161,32,162],[32,170,32,172],[32,173,32,203],[34,15,42,24],[34,28,35,28],[34,29,36,35],[34,40,36,50],[34,66,36,67],[34,68,39,73],[34,74,36,79],[34,80,36,83],[34,84,36,87],[34,93,36,104],[34,209,35,235],[35,26,35,27],[35,37,35,38],[35,55,35,63],[35,105,35,116],[35,117,35,118],[35,122,35,127],[35,132,35,133],[35,143,35,151],[35,167,35,168],[35,174,35,179],[35,184,35,185],[35,195,35,204],[36,209,100,235],[37,28,38,28],[37,29,39,39],[37,44,39,50],[37,56,39,64],[37,66,39,67],[37,74,39,79],[37,80,39,83],[37,84,39,87],[37,93,62,95],[37,96,51,104],[37,105,37,131],[37,132,37,164],[37,165,37,190],[38,26,38,27],[38,41,38,42],[38,53,38,54],[38,105,39,128],[38,129,39,133],[38,134,39,157],[38,158,39,162],[38,165,39,181],[38,182,39,185],[38,186,39,202],[38,203,39,206],[40,29,42,66],[40,67,42,87],[41,26,41,27],[41,105,42,119],[41,120,42,124],[41,125,42,137],[41,138,42,142],[41,143,42,155],[41,156,42,158],[41,160,42,170],[41,171,42,175],[41,176,42,186],[41,187,42,191],[41,192,42,202],[41,203,42,205],[43,15,44,24],[43,25,44,87],[43,105,44,119],[43,120,44,124],[43,125,44,137],[43,138,44,142],[43,143,44,155],[43,156,44,158],[43,160,44,170],[43,171,44,175],[43,176,44,186],[43,187,44,191],[43,192,44,202],[43,203,44,206],[45,105,46,119],[45,120,46,124],[45,125,46,137],[45,138,46,142],[45,143,46,155],[45,156,46,158],[45,160,46,170],[45,171,46,175],[45,176,46,186],[45,187,46,191],[45,192,46,202],[45,203,46,206],[47,15,48,87],[47,105,48,119],[47,120,48,123],[47,124,48,131],[47,133,48,141],[47,142,48,147],[47,148,48,156],[47,157,48,160],[49,11,69,14],[49,15,60,18],[49,19,49,31],[49,32,49,33],[49,105,51,111],[49,112,51,134],[49,135,51,140],[49,141,51,167],[49,168,51,171],[49,172,51,207],[50,21,52,85],[52,96,62,104],[52,105,53,128],[52,129,53,133],[52,134,53,151],[52,152,53,154],[52,155,53,157],[52,158,53,175],[52,176,53,178],[52,179,53,188],[52,189,53,203],[52,204,53,207],[53,21,53,34],[53,41,53,54],[53,75,53,80],[54,19,54,31],[54,34,54,35],[54,44,55,84],[54,105,55,128],[54,129,55,133],[54,134,55,151],[54,152,55,154],[54,155,55,157],[54,158,55,175],[54,176,55,178],[54,179,55,188],[54,189,55,203],[54,204,55,207],[56,19,60,27],[56,105,57,128],[56,129,57,133],[56,134,57,151],[56,152,57,154],[56,155,57,157],[56,158,57,175],[56,176,57,178],[56,179,57,188],[56,189,57,203],[56,204,57,207],[57,30,57,31],[57,40,57,41],[57,48,57,49],[57,63,57,64],[58,105,59,122],[58,123,59,127],[58,128,59,141],[58,142,59,154],[58,155,59,159],[58,164,59,178],[58,179,59,182],[59,28,60,35],[59,37,60,86],[60,105,62,113],[61,15,69,18],[61,19,61,32],[61,115,61,116],[61,128,61,142],[61,153,61,154],[61,162,61,176],[61,187,61,188],[62,20,67,86],[63,93,65,98],[63,99,65,104],[64,106,64,107],[64,112,64,113],[64,151,64,164],[64,171,64,184],[66,93,68,98],[66,99,68,104],[67,106,67,107],[67,112,67,113],[67,134,67,139],[67,148,67,155],[67,166,67,177],[68,19,68,31],[68,32,69,85],[69,88,80,92],[69,93,71,104],[70,11,77,14],[70,15,71,79],[70,106,70,107],[70,108,70,112],[70,115,70,116],[70,117,70,121],[70,124,70,125],[70,126,70,130],[70,133,70,134],[70,135,70,144],[70,146,70,147],[70,148,70,159],[70,161,70,162],[70,163,70,168],[72,15,75,86],[72,93,74,104],[72,155,74,163],[73,113,73,114],[73,124,73,129],[73,143,73,144],[73,166,73,167],[73,177,73,178],[75,93,77,104],[75,136,77,157],[76,15,77,24],[76,26,77,87],[76,107,76,108],[76,114,76,118],[76,126,76,127],[76,160,76,161],[76,168,76,172],[76,185,76,186],[78,11,99,14],[78,15,82,24],[78,68,82,73],[78,75,79,79],[78,93,80,104],[78,105,80,116],[78,154,80,165],[79,26,82,66],[79,118,79,119],[79,125,79,126],[79,127,79,133],[79,135,79,136],[79,137,79,143],[79,146,79,147],[79,167,79,168],[79,174,79,175],[79,176,79,182],[79,184,79,185],[79,186,79,192],[79,195,79,196],[80,75,81,83],[81,88,91,92],[82,93,82,109],[82,110,82,117],[82,118,82,120],[82,121,82,125],[82,126,82,128],[82,129,82,133],[82,134,82,136],[82,139,82,186],[83,15,85,24],[83,25,84,39],[83,40,84,43],[83,44,86,50],[83,68,86,73],[84,54,85,64],[84,65,85,66],[84,78,85,79],[84,85,85,86],[84,93,84,129],[84,131,84,132],[84,148,84,149],[84,157,84,197],[85,36,85,39],[85,40,85,43],[85,75,85,76],[85,82,85,83],[86,15,86,24],[86,25,86,27],[86,28,86,39],[86,93,86,109],[86,110,86,111],[86,120,86,121],[86,122,86,126],[86,127,86,132],[86,133,86,137],[86,144,86,153],[86,156,86,157],[86,165,86,166],[86,174,86,176],[86,177,86,197],[87,15,88,86],[88,93,88,109],[88,110,88,111],[88,112,88,118],[88,120,88,121],[88,122,88,131],[88,134,88,135],[88,136,88,145],[88,148,88,149],[88,150,88,157],[88,159,88,160],[88,162,88,197],[89,16,93,86],[90,93,90,102],[90,104,91,206],[92,88,95,92],[92,93,93,132],[92,135,93,184],[94,16,98,86],[94,95,95,120],[94,121,94,122],[94,131,95,146],[94,148,94,149],[94,150,95,154],[94,159,94,160],[94,161,95,171],[96,88,97,202],[98,98,98,99],[98,123,98,124]]}
[]
[{"$nulls":17},"定年制",{"$nulls":14},"求　　人　　票",{"$nulls":39},"         紹　介　期　限",{"$nulls":24},"紹　　介　　所　　専　　用　　整　　理　　欄",{"$nulls":111},"受付機関整理欄"]
[{"$nulls":14},"　"]
[{"$nulls":72},"　　    年       月  　    日",{"$nulls":24},"    Ａ　  Ｂ　  Ｃ　  Ｄ",{"$nulls":22},"受理番号",{"$nulls":21},"受理年月日",{"$nulls":21},"産業分類番号",{"$nulls":21},"職業分類番号",{"$nulls":22},"番号"]
[{"$nulls":17},"任期制",{"$nulls":14},"退職自衛官仙台無料職業紹介所"]
[{"$nulls":14},"　"]
[]
[{"$nulls":4},"［個人情報苦情及び相談窓口］一般財団法人自衛隊援護協会　事務局総務課（03‐5227‐5400）","　ては、左記にご連絡ください。遅滞なく回答いたします。  ","　はありません。なお、所定の項目にご記入いただけない場合には、適切な対応ができない場合があります。開示対象個人情報につい","　場合があります。求職者への提供、本人の同意がある場合又は法令に基づく場合を除き、取得した個人情報を第三者に提供すること","　ご記入いただいた個人情報は、求人者に適切な人材を紹介するために利用いたします。上記利用目的達成のため一部業務を委託する","［個人情報のお取扱いについて］個人情報保護管理者 事務局長","（記入上の注意）太線枠内を記入してください。"]
[{"$nulls":11},"ふりがな",{"$nulls":13},"せんだいしょうじ　かぶしきがいしゃ",{"$nulls":62},"就　業　時　間",{"$nulls":4},"就業時間",{"$nulls":26},"交替制",{"$nulls":32},"雇用期間"]
[{"$nulls":99},8,{"$nulls":3},"時",{"$nulls":4},"３０",{"$nulls":3},"分から",{"$nulls":13},"①",{"$nulls":6},"時",{"$nulls":4},"分",null,"～",{"$nulls":4},"時",{"$nulls":4},"分",{"$nulls":7},"　",null,null,"雇用期間の定め 無",{"$nulls":47},"機　関　名"]
[{"$nulls":11},"事業所名",{"$nulls":13},"仙台商事　株式会社",{"$nulls":155},"雇用期間",{"$nulls":8},12,{"$nulls":6},"ケ月間"]
[{"$nulls":158},"　",null,null,"雇用期間の定め 有",{"$nulls":28},"又は"]
[{"$nulls":99},17,{"$nulls":3},"時",{"$nulls":4},"３０",{"$nulls":3},"分まで",{"$nulls":13},"②",{"$nulls":6},"時",{"$nulls":4},"分",null,"～",{"$nulls":4},"時",{"$nulls":4},"分",{"$nulls":31},"○",null,null,"年",null,null,"○○",null,null,"月",null,null,"○○",null,null,"日まで"]
[{"$nulls":158},"・更新の有無"]
[{"$nulls":11},"代表者\n氏　　名",{"$nulls":13},"代表取締役社長       宮城　県治",{"$nulls":134},"　",null,null,"有",{"$nulls":3},"（",null,"　",null,"条件有",{"$nulls":7},"　",null,"原則更新",{"$nulls":10},"）",{"$nulls":3},"　",null,null,"無"]
[{"$nulls":126},"③",{"$nulls":6},"時",{"$nulls":4},"分",null,"～",{"$nulls":4},"時",{"$nulls":4},"分",{"$nulls":7},"・更新の条件：",{"$nulls":54},"地本 ・ 陸 ・ 海 ・ 空"]
[{"$nulls":158},"（",{"$nulls":47},"）"]
[{"$nulls":11},"所在地",{"$nulls":13},"〒",null,null,"123",{"$nulls":6},"-",null,null,"4567",{"$nulls":58},"※シフト制の場合　　　　　　　",{"$nulls":60},"・更新の上限：",{"$nulls":14},"　",null,null,"有",{"$nulls":5},"　",null,null,"無"]
[{"$nulls":126},"④",{"$nulls":6},"時",{"$nulls":4},"分",null,"～",{"$nulls":4},"時",{"$nulls":4},"分",{"$nulls":9},"（具体的な上限：",{"$nulls":15},"更新3回上限",{"$nulls":29},"）"]
[{"$nulls":26},"　宮城県仙台市宮城野区苦竹1　ABCビル　５F",{"$nulls":70},"(",null,"この間の",{"$nulls":12},"時間",{"$nulls":4},")",null,null,"有",{"$nulls":37},"・雇用期間経過後に正社員（期間の定め無）登用",{"$nulls":41},"）"]
[{"$nulls":121},"　",{"$nulls":38},"の可能性",{"$nulls":14},"有",{"$nulls":7},"無",{"$nulls":25},"年月日",{"$nulls":3},"・　　　・"]
[{"$nulls":97},"※変形労働時間制の場合　　　　　　　",{"$nulls":27},"特記事項"]
[{"$nulls":54},"☎",null,null,"022",{"$nulls":7},"（",null,"222",{"$nulls":7},"）",null,"1111",{"$nulls":42},"無",{"$nulls":32},"時間外",{"$nulls":44},"休憩時間",null,null,"\n\n\n分",60]
[{"$nulls":97},"(",null,"単位等：",{"$nulls":7},"1年",{"$nulls":9},")",{"$nulls":3},"　",{"$nulls":41},"　",null,null,"有",null,null,"（月平均時間",{"$nulls":12},20,null,null,"時間）",{"$nulls":5},"　",null,null,"無"]
[{"$nulls":11},"採用事務\n担　当　者",{"$nulls":13},"部課名",{"$nulls":6},"総務部",{"$nulls":15},"氏名",{"$nulls":5},"仙台市朗",{"$nulls":130},"　",{"$nulls":5},"　"]
[{"$nulls":93},"休日",{"$nulls":57},"　",{"$nulls":26},"年間休日数",{"$nulls":30},"担当者"]
[{"$nulls":54},"☎",null,null,"022",{"$nulls":7},"（",null,"222",{"$nulls":7},"）",null,"1111",{"$nulls":28},"　",null,"土曜",{"$nulls":4},"　",null,"日曜",{"$nulls":4},"　",null,"祝日",{"$nulls":4},"　",null,"会社カレンダーによる",{"$nulls":19},"　",null,"その他",{"$nulls":6},"（","（",null,null,"シフト制",{"$nulls":12},"）",{"$nulls":12},105,{"$nulls":6},"日",{"$nulls":8},"分"]
[]
[{"$nulls":93},"週休２日制",{"$nulls":86},"年間所定\n労働時間"]
[{"$nulls":11},"職種・年齢等",{"$nulls":3},"職　　種",{"$nulls":90},"　",null,null,"完全",{"$nulls":5},"　",null,null,"隔週",{"$nulls":5},"　",null,null,"月",{"$nulls":6},"回休",{"$nulls":5},"　",null,null,"無",{"$nulls":3},"　",null,null,"その他",{"$nulls":7},"(",null,"シフト制",{"$nulls":16},")",{"$nulls":14},2090,{"$nulls":10},"時間"]
[{"$nulls":19},"営業職",{"$nulls":86},"　",{"$nulls":6},"　",{"$nulls":6},"　",{"$nulls":13},"　",{"$nulls":6},"　",{"$nulls":71},"（",null,null,"(",null,null,"    ）"]
[{"$nulls":88},"賃金",{"$nulls":4},"賃金形態"]
[{"$nulls":106},"　",null,"年俸制",{"$nulls":7},"　",null,"月給制",{"$nulls":7},"　",null,"日給制",{"$nulls":12},"時間給制",{"$nulls":19},"　",null,"その他",{"$nulls":6},"（",{"$nulls":34},"）"]
[{"$nulls":106},"　"]
[{"$nulls":15},"雇用形態",{"$nulls":13},"正社員",{"$nulls":10},"正社員以外",{"$nulls":27},"採用　人員　",{"$nulls":5},"通勤",{"$nulls":5},3,{"$nulls":3},"人",{"$nulls":8},"賃金支払",{"$nulls":12},"　",{"$nulls":9},"　",{"$nulls":9},"　",{"$nulls":14},"　",{"$nulls":9},"　",{"$nulls":10},"　",{"$nulls":46},"その他（求人に関する特記事項)"]
[{"$nulls":26},"　",{"$nulls":10},"　",{"$nulls":14},"（",null,null,"嘱託社員",{"$nulls":8},"）",{"$nulls":40},"賃金締切日",{"$nulls":11},"　",{"$nulls":4},25,{"$nulls":5},"日",{"$nulls":3},"　",null,"その他（",{"$nulls":17},"）",{"$nulls":3},"支払日",{"$nulls":10},"　",null,"毎月　",{"$nulls":4},"末",{"$nulls":5},"日",{"$nulls":3},"　",null,"その他（",{"$nulls":18},"）"]
[]
[{"$nulls":29},"派遣・請負でない",{"$nulls":14},"有期雇用派遣",{"$nulls":11},"無期雇用派遣",{"$nulls":17},"住込",{"$nulls":9},"人",{"$nulls":8},"毎月の賃金（税込み）",null,null,"定期的に支払われる賃金",{"$nulls":8},"ａ基本給＜月額で表記＞",{"$nulls":59},"※年俸制の場合の年間給与額"]
[{"$nulls":26},"　",{"$nulls":14},"　",{"$nulls":11},"　",{"$nulls":51},{"v":180000,"d":"180,000"},{"$nulls":23},"円～",{"$nulls":4},{"v":200000,"d":"200,000"},{"$nulls":23},"円",{"$nulls":23},"円～",{"$nulls":20},"円"]
[]
[{"$nulls":29},"請負（他の事業所で就業する仕事の場合）",{"$nulls":75},"ｂ手当"]
[{"$nulls":26},"　",{"$nulls":78},"役職",{"$nulls":14},"手当",{"$nulls":4},20000,{"$nulls":12},"円～",{"$nulls":4},20000,{"$nulls":12},"円",{"$nulls":14},"手当",{"$nulls":15},"円～",{"$nulls":15},"円"]
[]
[{"$nulls":15},"役 職 名",{"$nulls":9},"○○○",{"$nulls":79},"資格",{"$nulls":14},"手当",{"$nulls":4},1000,{"$nulls":12},"円～",{"$nulls":4},10000,{"$nulls":12},"円",{"$nulls":14},"手当",{"$nulls":15},"円～",{"$nulls":15},"円"]
[]
[{"$nulls":15},"(労働施策総合推進法　施行規則第１条の３第１項に該当）",{"$nulls":89},"調整",{"$nulls":14},"手当",{"$nulls":4},10000,{"$nulls":12},"円～",{"$nulls":4},10000,{"$nulls":12},"円",{"$nulls":14},"手当",{"$nulls":15},"円～",{"$nulls":15},"円"]
[{"$nulls":15},"(定年以外の年齢制限がある場合の理由）"]
[{"$nulls":105},"（固定残業代：",{"$nulls":18},"時間分）",{"$nulls":17},"円～",{"$nulls":14},"円"]
[]
[{"$nulls":11},"職務内容",{"$nulls":3},"就業場所",{"$nulls":3},"（雇入れ直後）",{"$nulls":12},"　",null,"事業所に同じ。　同じでない場合は住所を記入。",{"$nulls":70},"ａ+ｂ",{"$nulls":6},{"v":211000,"d":"211,000"},{"$nulls":22},"円～",{"$nulls":5},{"v":240000,"d":"240,000 "},{"$nulls":26},"円",{"$nulls":3},"※固定残業代を採用する場合、固定残業時間を超える時間外労働分は追加で支給"]
[]
[]
[{"$nulls":96},"個人の状態に応じて支払われる賃金",{"$nulls":32},"手当",{"$nulls":22},"円",null,null,"～",{"$nulls":20},"円",null,null,"家族手当",{"$nulls":9},{"v":5000,"d":"5,000"},{"$nulls":14},"円"]
[{"$nulls":19},"（",null,"東北本",{"$nulls":13},"）線（",{"$nulls":5},"仙台",{"$nulls":13},"）駅・バス停から徒歩で（",{"$nulls":19},15,{"$nulls":6},"）分"]
[{"$nulls":19},"（転勤の可能性）",{"$nulls":14},"　",null,"あり",{"$nulls":4},"（　　　　　　　　　　　　　　　　　　　　　　　）",{"$nulls":87},"手当",{"$nulls":22},"円",null,null,"～",{"$nulls":20},"円",null,null,"配偶者",{"$nulls":24},"円"]
[]
[{"$nulls":19},"屋内の\n受動喫煙\n対策",{"$nulls":109},"手当",{"$nulls":22},"円",null,null,"～",{"$nulls":20},"円",null,null,"子供",{"$nulls":9},{"v":3000,"d":"3,000"},{"$nulls":14},"円"]
[{"$nulls":30},"　",null,"あり",{"$nulls":4},"（",null,null,"　",null,"禁煙",{"$nulls":5},"　",null,"喫煙室あり",{"$nulls":9},"）",null,null,"　",null,"その他"]
[{"$nulls":105},"時間外手当（月平均",{"$nulls":17},20,{"$nulls":4},"時間相当分）",{"$nulls":13},{"v":26000,"d":"26,000 "},{"$nulls":12},"円～",{"$nulls":8},{"v":29000,"d":"29,000 "},{"$nulls":14},"円"]
[{"$nulls":28},"特記事項：",{"$nulls":8},"野外に喫煙所あり"]
[{"$nulls":105},"通勤手当"]
[{"$nulls":15},"仕事の内容",{"$nulls":3},"（雇入れ直後）",{"$nulls":95},"　",null,"実費（最高",{"$nulls":10},{"v":25000,"d":"25,000 "},{"$nulls":14},"円まで）",{"$nulls":9},"　",null,"定額（",{"$nulls":21},"円）",{"$nulls":9},"　",null,"無"]
[{"$nulls":20},"※　主に行う業務を記入し、その他付随する\n業務もあれば併せてご記入下さい。",{"$nulls":94},"　",{"$nulls":37},"　"]
[{"$nulls":93},"昇給",{"$nulls":5},"制度"]
[{"$nulls":106},"　",null,"有",{"$nulls":3},"　",null,"無",{"$nulls":5},"ベースアップ込みの前年度実績",{"$nulls":30},{"v":1000,"d":"1,000 "},{"$nulls":13},"円～",{"$nulls":5},{"v":3000,"d":"3,000 "},{"$nulls":13},"円"]
[]
[{"$nulls":93},"賞与",{"$nulls":5},"制度"]
[{"$nulls":106},"　",null,"有",{"$nulls":3},"　",null,"無",{"$nulls":5},"前年度実績 年",{"$nulls":13},2,{"$nulls":5},"回",{"$nulls":3},"（",{"$nulls":3},2.5,{"$nulls":7},"月分又は",{"$nulls":21},"万円）"]
[{"$nulls":19},"（変更の範囲）",{"$nulls":12},"○○業務"]
[{"$nulls":88},"福利厚生等",{"$nulls":4},"加入保険"]
[{"$nulls":11},"必須技能等",{"$nulls":3},"必要な経験（年数）・技能・知識・免許資格",{"$nulls":90},"　",null,"雇用",{"$nulls":6},"　",null,"労災",{"$nulls":6},"　",null,"健康",{"$nulls":6},"　",null,"厚生年金",{"$nulls":10},"　",null,"退職金共済",{"$nulls":12},"　",null,"財形"]
[{"$nulls":106},"　",{"$nulls":17},"　",{"$nulls":9},"　",{"$nulls":12},"　",{"$nulls":16},"　"]
[{"$nulls":15},"　　　　　・普通自動車運転免許　必須\n　　　　　・大型自動車運転免許　あれば尚可",{"$nulls":77},"退職金制度",{"$nulls":61},"通　学"]
[{"$nulls":106},"制度",{"$nulls":6},"　",null,"有（最低",{"$nulls":8},3,{"$nulls":5},"年勤続）",{"$nulls":7},"・",{"$nulls":4},"　",null,"無",{"$nulls":20},"　",null,"可",{"$nulls":8},"　",null,"否"]
[{"$nulls":112},"　",{"$nulls":30},"　",{"$nulls":20},"　",{"$nulls":15},"　"]
[{"$nulls":93},"定年制",{"$nulls":18},"　",{"$nulls":23},"再雇用又は勤務延長　",{"$nulls":27},"　",{"$nulls":15},"　"]
[{"$nulls":15},"学　　歴",{"$nulls":10},"不問",{"$nulls":80},"　",null,"有（",{"$nulls":4},65,{"$nulls":4},"歳）",{"$nulls":6},"　",null,"無",{"$nulls":31},"　",null,"有（",{"$nulls":5},70,{"$nulls":5},"歳）",{"$nulls":8},"・",null,"　",null,"無",{"$nulls":3},"　"]
[]
[{"$nulls":11},"事業所の概要",{"$nulls":3},"主たる　生産品目　　事業内容",{"$nulls":52},"創立　　設立",{"$nulls":6},"西暦",{"$nulls":17},"住宅",{"$nulls":11},"単身者用",{"$nulls":48},"世帯用"]
[{"$nulls":26},"※主な登録業務",{"$nulls":91},"　",null,"有（",{"$nulls":4},"　",null,"入居可",{"$nulls":7},"　",null,"不可）",{"$nulls":8},"　",null,"無",{"$nulls":18},"　",null,"有（",{"$nulls":4},"　",null,"入居可",{"$nulls":7},"　",null,"不可）",{"$nulls":8},"　",null,"無"]
[{"$nulls":75},1999]
[{"$nulls":84},"年",{"$nulls":3},"備　　考"]
[{"$nulls":93},"・採用希望期限",{"$nulls":16},2000,{"$nulls":7},"年",null,null,3,{"$nulls":4},"月",null,null,31,{"$nulls":4},"日",{"$nulls":4},"指定のない場合の有効期間は３か月間です。"]
[{"$nulls":15},"従業員数",{"$nulls":9},"○○○",{"$nulls":14},"人",{"$nulls":3},"資本金",{"$nulls":23},"労働\n組合"]
[{"$nulls":54},"○○○",{"$nulls":10},"円",{"$nulls":12},"有",{"$nulls":6},"無",{"$nulls":7},"・採用を希望する者の自衛隊時の階級",{"$nulls":37},"　",null,"特になし",{"$nulls":14},"　",null,"あり（",{"$nulls":47},"）"]
[{"$nulls":25},"（うち女子",{"$nulls":10},"○○",{"$nulls":3},"人）",{"$nulls":34},"　",{"$nulls":6},"　",{"$nulls":48},"　"]
[{"$nulls":15},"全従業員数",{"$nulls":12},"○○○",{"$nulls":11},"人",{"$nulls":52},"・試用期間",{"$nulls":16},"　",null,"無",{"$nulls":7},"　",null,"有（",{"$nulls":4},3,{"$nulls":5},"月）",{"$nulls":10},"労働条件",{"$nulls":11},"　",null,"同じ",{"$nulls":6},"　",null,"異なる",{"$nulls":6},"（",{"$nulls":23},"）"]
[{"$nulls":15},"（年商額など最近の業績及び会社のPRなど）"]
[{"$nulls":93},"・選考方法",{"$nulls":16},"　",null,"面　接",{"$nulls":7},"　",null,"書類選考",{"$nulls":11},"　",null,"筆記試験",{"$nulls":11},"　",null,"その他",{"$nulls":7},"（","（",null,null,"適性検査",{"$nulls":35},"）"]
[{"$nulls":16},"・前年度売り上げ実績：○○億円\n・事業展開及び取引先の拡大により、前年度と比較し大幅に売上を伸ばしています。"]
[{"$nulls":93},"・その他"]
[]
[{"$nulls":88},"確認事項",{"$nulls":4},"・退職自衛官の採用に関する確認事項",{"$nulls":41},"（確認した場合は□を黒塗りして下さい。）"]
[]
[{"$nulls":16},"・安定した事業と収益の見込みから、将来性に自信を持てる\n会社です。",{"$nulls":78},"○第１項～第４項、第６項",{"$nulls":25},"　",{"$nulls":9},"○第5項に該当（",{"$nulls":16},"　",null,"する",{"$nulls":8},"　",null,"しない　）"]
[]
[{"$nulls":88},"予備自衛官等希望者の採用（採用をご検討いただける場合は□を黒塗りして下さい。両方を選択いただくことも可能です。）"]
[]
[{"$nulls":98},"　",null,"即応予備自衛官",{"$nulls":22},"　",null,"予備自衛官"]
[]
[]
[{"$nulls":87},"　　　　　　"]
[]
[{"$nulls":87},"　"]
{"$rows_empty":63}
[{"$nulls":5},"■",null,null,2,2]
[{"$nulls":8},2,2]

{"sheet":"確認事項①(閲覧のみ)","index":3,"n_rows":57,"n_cols":22,"rows_kept":57,"merged":[[0,28,0,32],[1,1,1,17],[3,0,3,32],[4,0,4,32],[5,0,5,32],[6,0,6,15],[8,21,8,30],[10,0,10,32],[11,0,11,32],[13,0,13,32],[14,0,14,32],[15,0,15,32],[16,0,16,32],[17,0,17,32],[19,0,19,32],[20,0,20,32],[21,0,21,32],[22,0,22,32],[23,0,23,32],[24,0,24,32],[25,0,25,32],[26,0,26,32],[27,0,27,32],[28,0,28,32],[29,0,29,32],[30,0,30,32],[31,0,31,32],[32,0,32,32],[33,0,33,32],[34,0,34,32],[35,0,35,32],[36,0,36,32],[37,0,37,32],[39,0,39,32],[40,0,40,32],[41,0,41,32],[42,0,42,32],[43,0,43,32],[44,0,44,32],[45,0,45,32],[46,0,46,32],[47,0,47,32],[48,0,48,32],[50,0,50,32],[51,0,51,32],[52,0,52,32],[53,0,53,32],[55,0,55,32],[56,0,56,32],[58,24,58,32],[60,28,60,30],[62,0,62,32],[64,0,64,32],[65,0,65,32],[66,0,66,32],[67,0,67,32],[68,0,68,32],[69,0,69,32],[70,0,70,32],[71,0,71,32],[72,0,72,32],[73,0,73,32],[74,0,74,32],[75,0,75,32],[76,0,76,32],[77,0,77,32],[78,0,78,32],[79,0,79,32],[80,0,80,32],[81,0,81,32],[82,0,82,32],[83,0,83,32],[84,0,84,32],[85,0,85,32],[86,0,86,32],[87,0,87,32],[88,0,88,32],[89,0,89,32],[90,0,90,32],[91,0,91,32],[92,0,92,32],[93,0,93,32],[94,0,94,32],[95,0,95,32],[96,0,96,32],[97,0,97,32],[98,0,98,32],[99,0,99,32],[100,0,100,32],[101,0,101,32],[102,0,102,32],[103,0,103,32],[104,0,104,32],[105,0,105,32],[106,0,106,32],[107,0,107,32],[108,0,108,32],[109,0,109,32],[110,0,110,32],[111,0,111,32],[112,0,112,32],[113,0,113,32],[114,0,114,32],[115,0,115,32],[116,0,116,32],[117,0,117,32],[118,0,118,32],[119,0,119,32],[120,0,120,32],[121,0,121,32],[122,0,122,32],[123,0,123,32],[124,0,124,32],[125,0,125,32],[126,0,126,32],[127,0,127,32],[128,0,128,32],[129,0,129,32],[130,0,130,32],[131,0,131,32],[132,0,132,32],[133,0,133,32],[134,0,134,32],[135,0,135,32],[136,0,136,32],[137,0,137,32],[138,0,138,32],[139,0,139,32],[140,0,140,32],[141,0,141,32],[142,0,142,32],[143,0,143,32],[144,0,144,32],[145,0,145,32],[146,0,146,32],[147,0,147,32],[148,0,148,32],[149,0,149,32],[150,0,150,32],[151,0,151,32],[152,0,152,32],[153,0,153,32],[154,0,154,32],[155,0,155,32],[156,0,156,32],[157,0,157,32],[158,0,158,32],[159,0,159,32],[160,0,160,32],[161,0,161,32],[162,0,162,32],[163,0,163,32],[164,0,164,32],[165,0,165,32],[166,0,166,32],[167,0,167,32],[168,0,168,32],[169,0,169,32],[170,0,170,32],[171,0,171,32],[172,0,172,32],[173,0,173,32],[174,0,174,32],[175,0,175,32],[176,0,176,32],[177,0,177,32],[178,0,178,32],[179,0,179,32],[180,0,180,32],[181,0,181,32],[182,0,182,32],[183,0,183,32],[184,0,184,32],[185,0,185,32],[186,0,186,32],[187,0,187,32],[188,0,188,32],[189,0,189,32],[190,0,190,32],[191,0,191,32],[192,0,192,32],[193,0,193,32],[194,0,194,32],[195,0,195,32],[196,0,196,32],[197,0,197,32],[198,0,198,32],[199,0,199,32],[200,0,200,32],[201,0,201,32],[202,0,202,32],[203,0,203,32],[204,0,204,32],[205,0,205,32],[206,0,206,32],[207,0,207,32],[208,0,208,32],[209,0,209,32],[210,0,210,32],[211,0,211,32],[212,0,212,32],[213,0,213,32],[214,0,214,32],[215,0,215,32],[216,0,216,32],[217,0,217,32],[218,0,218,32],[219,0,219,32],[220,0,220,32],[221,0,221,32],[222,0,222,32],[223,0,223,32],[224,0,224,32],[225,0,225,32],[226,0,226,32],[227,0,227,32],[228,0,228,32],[229,0,229,32],[230,0,230,32],[231,0,231,32],[232,0,232,32],[233,0,233,32],[234,0,234,32],[235,0,235,32],[236,0,236,32],[237,0,237,32],[238,0,238,32],[239,0,239,32],[240,0,240,32],[241,0,241,32],[242,0,242,32],[243,0,243,32],[244,0,244,32],[245,0,245,32],[246,0,246,32],[247,0,247,32],[248,0,248,32],[249,0,249,32],[250,0,250,32],[251,0,251,32],[252,0,252,32],[253,0,253,32],[254,0,254,32],[255,0,255,32],[256,0,256,32],[257,0,257,32],[258,0,258,32],[259,0,259,32],[260,0,260,32],[261,0,261,32],[262,0,262,32],[263,0,263,32],[264,0,264,32],[265,0,265,32],[266,0,266,32],[267,0,267,32],[268,0,268,32],[269,1,270,5],[269,6,269,29],[270,6,270,17],[270,18,270,29],[271,1,281,5],[271,6,274,6],[271,7,274,17],[271,18,274,29],[275,6,281,6],[275,7,281,17],[275,18,281,29],[282,1,292,5],[282,6,287,6],[282,7,287,17],[282,18,284,18],[282,19,284,29],[285,18,288,18],[285,19,288,29],[288,6,292,6],[288,7,292,17],[289,18,292,29],[294,0,294,32],[295,0,295,32],[296,0,296,32],[297,0,297,32],[298,0,298,32],[299,0,299,32],[300,2,300,25],[300,26,300,29],[301,2,301,25],[301,26,301,29],[302,0,302,32],[303,0,303,32],[304,0,304,32],[305,0,305,32],[306,0,306,32],[307,0,307,32],[308,0,308,32],[309,0,309,32],[310,0,310,32],[311,0,311,32],[312,0,312,32],[313,0,313,32],[314,0,314,32],[315,0,315,32],[316,0,316,32],[317,0,317,32],[318,0,318,32],[319,0,319,32],[320,0,320,32],[321,0,321,32],[322,0,322,32],[323,0,323,32],[324,0,324,32],[325,0,325,32],[326,0,326,32],[327,0,327,32],[328,0,328,32],[329,0,329,32],[330,0,330,32],[331,0,331,32],[332,0,332,32],[333,0,333,32],[334,0,334,32],[335,0,335,32],[336,0,336,32],[337,0,337,32],[338,0,338,32],[339,0,339,32],[340,0,340,32],[341,0,341,32],[342,0,342,32],[343,0,343,32],[344,0,344,32],[345,0,345,32],[346,0,346,32],[347,0,347,32],[348,0,348,32],[349,0,349,32],[350,0,350,32],[351,0,351,32],[352,0,352,32],[353,0,353,32],[354,0,354,32],[355,0,355,32],[356,0,356,32],[357,0,357,32],[358,0,358,32],[359,0,359,32],[360,0,360,32],[361,0,361,32],[362,0,362,32],[363,0,363,32],[364,0,364,32],[365,0,365,32],[366,0,366,32],[367,0,367,32],[368,0,368,32],[369,0,369,32],[370,0,370,32],[371,0,371,32],[372,0,372,32],[373,0,373,32],[374,0,374,32],[375,0,375,32],[376,0,376,32],[377,0,377,32],[378,0,378,32],[379,0,379,32],[380,0,380,32],[381,0,381,32],[382,0,382,32],[383,0,383,32],[384,0,384,32],[385,0,385,32],[386,0,386,32],[387,0,387,32],[388,0,388,32],[389,0,389,32],[390,0,390,32],[391,0,391,32],[392,0,392,32],[393,0,393,32],[394,0,394,32],[395,0,395,32],[396,0,396,32],[397,0,397,32],[398,0,398,32],[399,0,399,32],[400,0,400,32],[401,0,401,32],[402,0,402,32],[403,0,403,32],[404,0,404,32],[405,0,405,32],[406,0,406,32],[407,0,407,32],[408,0,408,32],[409,0,409,32],[410,0,410,32],[411,0,411,29],[412,0,412,32],[414,3,414,9],[414,10,414,29],[415,3,415,9],[415,10,415,29],[416,3,416,9],[416,10,416,29],[417,3,417,9],[417,10,417,29],[418,3,418,9],[418,10,418,29],[419,3,419,9],[419,10,419,29],[420,3,420,9],[420,10,420,29],[421,3,421,9],[421,10,421,29]]}
[]
[null,"退職自衛官の求人をお考えの企業　　様"]
[]
["　退職自衛官である求職者を紹介するに当たっては、求人企業の皆様から下記について同意等を得"]
["る必要があることから、これをご確認の上、確認事項欄にご記入をお願い致します。"]
["　なお、確認書の内容と事実に相違が確認された場合は、退職自衛官を紹介できない場合がござい"]
["ますので、あらかじめご承知おきください。　　　　　　　　　　　　　　　　　　　　"]
[]
[{"$nulls":21},"一般財団法人自衛隊援護協会"]
[]
[]
["退職自衛官の採用に関する確認事項"]
[]
["１　企業名等の公表に関する確認"]
["　　防衛大臣の就職の援助により、若年定年等隊員（自衛隊法（昭和２９年法律第１６５号）第６"]
["　５条の２第２項第１号に規定する若年定年等隊員をいう。）を採用した場合には、自衛隊法第６"]
["　５条の１３の規定に基づき、貴社名及び採用した当該隊員の貴社における役職・地位等について、"]
["　防衛省令の定めるところにより公表されることについて同意すること。"]
[]
["２　公契約関係競売等妨害罪等に関する確認"]
["（１） 貴社の役員等（取締役、会計参与、監査役、執行役、業務を執行する社員、支配人、理事"]
["　　若しくは監事又はこれらの者であった者をいう。以下同じ。）が、過去２年以内に公契約関"]
["　　係競売等妨害罪（刑法（明治４０年法律第４５号）第９６条の６に規定する罪をいう。）又"]
["　　は贈賄罪（刑法第１９８条に規定する罪をいう。）に当たる事件として、公訴が提起された"]
["　　（無罪の判決等がなされた場合を除く。以下同じ。）又は有罪の判決がなされた（刑の執行"]
["　　が終わった等の場合を除く。以下同じ。）ことがないこと。"]
["（２） 貴社の役員等が過去２年以内に、収賄罪（刑法第１９７条から第１９７条の４に規定する"]
["　　罪をいう。）に当たる事件として、公訴が提起された又は有罪の判決がなされた公務員（公"]
["　　務員であった者を含む。）に対し、賄賂の供与若しくはその約束をしたことがないこと。"]
[]
["3　個人情報の取扱いに関する確認"]
["　　一般財団法人自衛隊援護協会から提供された個人情報の取扱いについて、次に掲げる項目につ"]
["　いて遵守することに同意すること。"]
["（１） 採用選考等に関わらない第三者への個人情報の開示、提供及び漏洩をしない。"]
["　　（個人情報：履歴書、職務経歴書等の個人を特定できる情報）"]
["（２） 選考不採用、又は採用入社に至らなかった応募者の個人情報は、第三者に漏洩しないよう、"]
["　　速やかにデータを削除し、書類はシュレッダー等にて破棄あるいは返却する。"]
["（３） 利用目的の達成に必要な範囲を超えて、個人情報を取り扱わない。"]
[]
["4　反社会的勢力の排除に関する確認"]
["（１）貴社（主要な出資者、役員、及びそれに準ずる者を含む。以下同じ）が暴力団、暴力団員"]
["　　・準構成員、暴力団関係企業、特殊知能暴力集団の関係者その他公益に反する行為をなす者"]
["　　（以下「反社会的勢力」という。）でないこと、過去５年間もそうでなかったこと及び反社"]
["　　会的勢力と資金提供、便宜供与その他いかなる関係も有しないことを表明し、かつ将来にわ"]
["　　たっても反社会的勢力とのいかなる関係も有しないこと。"]
["（２）自ら又は第三者を利用して、暴力的な要求行為、法的な責任を超えた不当な要求行為、取"]
["　　引に関して、脅迫的な言動をし、又は暴力を用いる行為、風説を流布し、偽計を用い又は威"]
["　　力を用いて相手方の信用を毀損し、又は相手方の業務を妨害する行為、及びその他これらに"]
["　　準ずる行為を行わないこと。"]
[]
["５　一定の労働関係法令違反に関する申告"]
["　　職業安定法第５条の5第3号に規定する求人不受理の対象（一定の労働関係法令に関し、　　"]
["　法律に基づく処分等が講じられ一定期間が経過していない）に該当しているか否かの申告"]
["　（対象となる規定等は裏面をご覧ください。）"]
[]
["6　その他の確認"]
["　　確認した内容に変動があった場合は、速やかに通知することに同意すること。"]

{"sheet":"確認事項②(閲覧のみ)","index":4,"n_rows":20,"n_cols":4,"rows_kept":20,"merged":[[2,1,2,3],[5,1,7,1],[5,2,7,2],[5,3,7,3],[8,1,10,1],[8,2,10,2],[8,3,10,3],[11,1,14,1],[11,2,14,2],[11,3,14,3]]}
[]
[]
[null,"求人不受理の対象となる場合と期間"]
[]
[null,"対象となる規定","講じられた措置等","求人不受理期間"]
[null,"労働基準法及び最低賃金法に関する規定","１年間に２回以上、同一の対象条項違反により是正指導を受けた場合","法違反の是正後６か月経過するまで"]
[]
[]
[null,"労働基準法及び最低賃金法に関する規定","対象条項違反により送検され、公表された場合","送検された日から１年経過するまで"]
[]
[]
[null,"職業安定法、男女雇用機会均等法、育児・介護休業法及び労働施策総合推進法に関する規定","対象条項に違反し、法違反の是正を求める勧告に従わず、公表された場合","法違反の是正後６か月経過するまで"]
[]
[]
[]
[]
[]
[null,"職業安定法、男女雇用機会均等法及び育児・介護休業法規定等、詳しくは"]
[null,"求人不受理について（厚生労働省）"]
[null," https://www.mhlw.go.jp/content/ 11600000/000602020.pdf"]

{"sheet":"予備自衛官制度の概要(閲覧のみ)","index":5,"n_rows":0,"n_cols":0,"rows_kept":0}

{"sheet":"求人票(裏)","index":6,"n_rows":38,"n_cols":20,"rows_kept":38,"hidden":true,"merged":[[1,1,1,17],[1,18,1,19],[2,1,3,17],[2,18,3,19],[5,1,12,1],[5,2,6,5],[5,6,6,17],[5,19,6,24],[7,2,7,5],[7,6,7,17],[7,19,36,24],[8,2,8,5],[8,6,8,17],[9,2,9,5],[9,6,9,17],[10,2,10,5],[10,6,10,17],[11,2,11,5],[11,6,11,17],[12,2,12,5],[12,6,12,17],[13,1,36,1],[13,2,14,4],[13,5,14,7],[13,8,14,10],[13,11,14,14],[13,16,14,17],[13,18,14,18],[14,15,15,15],[15,2,16,4],[15,5,16,7],[15,8,16,10],[15,12,16,14],[15,16,16,17],[15,18,16,18],[17,2,18,4],[17,5,20,7],[17,8,18,10],[17,11,18,14],[17,15,20,15],[17,16,18,17],[17,18,18,18],[19,2,20,4],[19,8,20,10],[19,13,20,14],[19,16,20,17],[19,18,20,18],[21,2,22,4],[21,5,24,7],[21,8,22,10],[21,11,22,14],[21,15,24,15],[21,16,22,17],[21,18,22,18],[23,2,24,4],[23,8,24,10],[23,13,24,14],[23,16,24,17],[23,18,24,18],[25,2,26,4],[25,5,28,7],[25,8,26,10],[25,11,26,14],[25,15,28,15],[25,16,26,17],[25,18,26,18],[27,2,28,4],[27,8,28,10],[27,13,28,14],[27,16,28,17],[27,18,28,18],[29,2,30,4],[29,5,32,7],[29,8,30,10],[29,11,30,14],[29,15,32,15],[29,16,30,17],[29,18,30,18],[31,2,32,4],[31,8,32,10],[31,13,32,14],[31,16,32,17],[31,18,32,18],[33,2,34,4],[33,5,36,7],[33,8,34,10],[33,11,34,14],[33,15,36,15],[33,16,34,17],[33,18,34,18],[35,2,36,4],[35,8,36,10],[35,13,36,14],[35,16,36,17],[35,18,36,18],[37,2,37,24]]}
[]
[null,"事業所名",{"$nulls":16},"紹介所整理番号"]
[null,{"$f":"IF(ISBLANK('求人票(表)'!V14),\"\",'求人票(表)'!V14)","v":""},{"$nulls":16},{"$f":"IF(ISBLANK('求人票(表)'!DV9),\"\",'求人票(表)'!DM9&'求人票(表)'!DT9&TEXT('求人票(表)'!DV9,\"0000\"))","v":""}]
[]
[]
[null,"情 報 処 置 欄","年月日",{"$nulls":3},"処　　　置　　　概　　　要",{"$nulls":11},"取扱者","備考"]
[{"$nulls":18},"㊞"]
[]
[]
[]
[]
[]
[]
[null,"紹 　介　 状　 況　 欄","紹介年月日",null,null,"自 衛 隊",null,null,"所　　属",null,null,"氏　　　　　　　名",{"$nulls":3},"採","採用年月日",null,"採否結果"]
[{"$nulls":15},"否"]
[null,null,"確認事項",null,null,"区　  分",null,null,"階　　級",{"$nulls":3},"（年　　　令）",{"$nulls":3},"不調理由等",null,"確 認  ㊞"]
[{"$nulls":15},"別"]
[]
[]
[{"$nulls":13},"（　　）"]
[]
[]
[]
[{"$nulls":13},"（　　）"]
[]
[]
[]
[{"$nulls":13},"（　　）"]
[]
[]
[]
[{"$nulls":13},"（　　）"]
[]
[]
[]
[{"$nulls":13},"（　　）"]
[]
[null,null,"※紹介年月日において、退職自衛官の採用に関する確認事項に変動がないことを確認し、当該確認が取れた場合には「確認済」を○で囲むこと。"]

{"sheet":"宮城センター用","index":7,"n_rows":14,"n_cols":53,"rows_kept":14,"hidden":true}
[]
[{"$f":"+BA4","v":""}]
["受付No","受理機関","部署ＩＤ","受理月日","今月分","四半期","企業等名","ふりがな","所在地","所在地２","就業場所","従業員数","資本 億\n億＝10000万","資本 万","雇用協","職種","採用\n人員","年齢","必須技能等","即応","登録\n状況","就業時間","休日","週休\n二日制","賃金形態","基本給","基本給２","Ａ＋Ｂ","Ａ＋Ｂ２","皆手当","配手当","子手当","通勤手当","他手当","賞与（前年度実績）","退職金","定年制","再雇用","担当者","松島求人","紹介期限","雇用形態","重点\n企業","即自可能\n企業","予備自可能\n企業","登録\n番号","援護協会\n産業分類","援護協会\n職種番号","業種\n（援協）","業種\n（方面）","職業分類\n（援協）","職業分類\n（方面)","定・\n任区分"]
[null,{"$f":"'求人票(表)'!HC14","v":0},null,{"$f":"IF(ISBLANK('求人票(表)'!HB24),\"\",IF(ISNUMBER('求人票(表)'!HB24),'求人票(表)'!HB24,IF(ISERROR(FIND(\".\",'求人票(表)'!HB24)),DATE(_xlfn.NUMBERVALUE(LEFT('求人票(表)'!HB24,FIND(\"．\",'求人票(表)'!HB24)-1))+2018,INT(_xlfn.NUMBERVALUE(MID('求人票(表)'!HB24,FIND(\"．\",'求人票(表)'!HB24)+1,LEN('求人票(表)'!HB24)-FIND(\"．\",'求人票(表)'!HB24)))),RIGHT(MID('求人票(表)'!HB24,FIND(\"．\",'求人票(表)'!HB24)+1,LEN('求人票(表)'!HB24)-FIND(\"．\",'求人票(表)'!HB24)),LEN(MID('求人票(表)'!HB24,FIND(\"．\",'求人票(表)'!HB24)+1,LEN('求人票(表)'!HB24)-FIND(\"．\",'求人票(表)'!HB24)))-FIND(\"．\",MID('求人票(表)'!HB24,FIND(\"．\",'求人票(表)'!HB24)+1,LEN('求人票(表)'!HB24)-FIND(\"．\",'求人票(表)'!HB24))))),DATE(_xlfn.NUMBERVALUE(LEFT('求人票(表)'!HB24,FIND(\".\",'求人票(表)'!HB24)-1))+2018,INT(_xlfn.NUMBERVALUE(MID('求人票(表)'!HB24,FIND(\".\",'求人票(表)'!HB24)+1,LEN('求人票(表)'!HB24)-FIND(\".\",'求人票(表)'!HB24)))),RIGHT(MID('求人票(表)'!HB24,FIND(\".\",'求人票(表)'!HB24)+1,LEN('求人票(表)'!HB24)-FIND(\".\",'求人票(表)'!HB24)),LEN(MID('求人票(表)'!HB24,FIND(\".\",'求人票(表)'!HB24)+1,LEN('求人票(表)'!HB24)-FIND(\".\",'求人票(表)'!HB24)))-FIND(\".\",MID('求人票(表)'!HB24,FIND(\".\",'求人票(表)'!HB24)+1,LEN('求人票(表)'!HB24)-FIND(\".\",'求人票(表)'!HB24))))))))","v":""},null,null,{"$f":"'求人票(表)'!V14","v":0},{"$f":"'求人票(表)'!V12","v":0},{"$f":"IF(OR(MID('求人票(表)'!W23,3,1)=\"都\",MID('求人票(表)'!W23,3,1)=\"道\",MID('求人票(表)'!W23,3,1)=\"府\",MID('求人票(表)'!W23,3,1)=\"県\",MID('求人票(表)'!W23,4,1)=\"県\"),LEFT('求人票(表)'!W23,IF(OR(LEFT('求人票(表)'!W23)=\"神\",LEFT('求人票(表)'!W23)=\"和\",LEFT('求人票(表)'!W23)=\"鹿\"),4,3)),\"\")","v":""},{"$f":"CONCATENATE(MID('求人票(表)'!W23,LEN(I4)+1,LEN('求人票(表)'!W23)-LEN(I4)))","v":""},{"$f":"IF('求人票(表)'!AA52=\"■\",LEFT('求人票(表)'!AE52,7),'求人票(表)'!R53)","v":0},{"$f":"'求人票(表)'!Y95","v":{"v":0,"d":"0 "}},null,{"$f":"'求人票(表)'!AW93","v":{"v":0,"d":"0 "}},{"$f":"IF(OR('求人票(表)'!HE96=\"雇\",'求人票(表)'!HE96=\"雇10\"),\"〇\",\"\")","v":""},{"$f":"'求人票(表)'!V33","v":0},{"$f":"SUM('求人票(表)'!BY37:CB45)","v":0},{"$f":"'求人票(表)'!L50","v":0},{"$f":"'求人票(表)'!L82","v":0},{"$f":"IF(OR('求人票(表)'!HE96=\"即\",'求人票(表)'!HL96=\"即\"),\"〇\",IF(OR('求人票(表)'!HE96=\"即10\",,'求人票(表)'!HL96=\"即10\"),\"〇10\",\"\"))","v":""},{"$f":"'求人票(表)'!GX96","v":0},{"$f":"IF('求人票(表)'!DN24=\"■\",'求人票(表)'!DM12,TEXT('求人票(表)'!CR13,\"00\")&TEXT('求人票(表)'!DA13,\"00\")&\"～\"&TEXT('求人票(表)'!CR16,\"00\")&TEXT('求人票(表)'!DA16,\"00\"))","v":"0000～0000"},{"$f":"IF('求人票(表)'!CY30=\"■\",LEFT('求人票(表)'!DA30,1),\"\")&IF('求人票(表)'!DF30=\"■\",LEFT('求人票(表)'!DH30),\"\")&IF('求人票(表)'!DM30=\"■\",LEFT('求人票(表)'!DO30,1),\"\")&IF('求人票(表)'!DT30=\"■\",LEFT('求人票(表)'!DV30,1),\"\")&IF('求人票(表)'!FA30=\"\",\"\",'求人票(表)'!FA30)","v":""},{"$f":"IF('求人票(表)'!CY33=\"■\",'求人票(表)'!DB33,IF('求人票(表)'!DH33=\"■\",'求人票(表)'!DK33,IF('求人票(表)'!FL33=\"■\",'求人票(表)'!FO33,IF('求人票(表)'!EG33=\"■\",'求人票(表)'!EJ33,IF('求人票(表)'!DQ33=\"■\",'求人票(表)'!DT33&'求人票(表)'!DW33&LEFT('求人票(表)'!EA33,1),\"\")))))","v":""},{"$f":"IF('求人票(表)'!FB36=\"■\",'求人票(表)'!FN36,IF('求人票(表)'!CY36=\"■\",'求人票(表)'!DA36,IF('求人票(表)'!DI36=\"■\",'求人票(表)'!DK36,IF('求人票(表)'!DS36=\"■\",'求人票(表)'!DU36,IF('求人票(表)'!EF36=\"■\",'求人票(表)'!EH36,\"\")))))","v":""},{"$f":"'求人票(表)'!CX42","v":{"v":0,"d":"¥0"}},{"$f":"'求人票(表)'!EA42","v":{"v":0,"d":"¥0"}},{"$f":"'求人票(表)'!DE53","v":{"v":0,"d":"¥0"}},{"$f":"'求人票(表)'!EH53","v":{"v":0,"d":"¥0"}},null,{"$f":"'求人票(表)'!GD58","v":{"v":0,"d":"¥0"}},{"$f":"'求人票(表)'!GD60","v":{"v":0,"d":"¥0"}},{"$f":"IF('求人票(表)'!DH65=\"■\",'求人票(表)'!DJ65&'求人票(表)'!DU65&'求人票(表)'!EJ65,IF('求人票(表)'!ET65=\"■\",'求人票(表)'!EV65&'求人票(表)'!FC65&'求人票(表)'!FR65,IF('求人票(表)'!GK65=\"■\",'求人票(表)'!GM65,\"\")))","v":""},null,{"$f":"IF('求人票(表)'!GK71=\"■\",'求人票(表)'!GM71,IF('求人票(表)'!DH71=\"■\",IF('求人票(表)'!EE71=\"\",'求人票(表)'!DJ71,\"年\"&'求人票(表)'!EE71&'求人票(表)'!EK71&IF('求人票(表)'!ES71=\"\",,\"　年\"&'求人票(表)'!ES71&\"月分\"&IF('求人票(表)'!FJ71=\"\",\"\",\"　又は\"))&IF('求人票(表)'!FJ71=\"\",\"\",\"　\"&'求人票(表)'!FJ71&\"万円\")),\"\"))","v":""},{"$f":"IF('求人票(表)'!EM77=\"■\",'求人票(表)'!DU80,IF('求人票(表)'!DF77=\"■\",IF('求人票(表)'!DQ77=\"\",\"有\",'求人票(表)'!DQ77),\"\"))","v":""},{"$f":"IF('求人票(表)'!DS80=\"■\",'求人票(表)'!DU80,IF('求人票(表)'!CZ80=\"■\",IF('求人票(表)'!DG80=\"\",\"有\",'求人票(表)'!DG80),\"\"))","v":""},{"$f":"IF('求人票(表)'!GK80=\"■\",'求人票(表)'!GM80,IF('求人票(表)'!FI80=\"■\",IF('求人票(表)'!FQ80=\"\",\"有\",'求人票(表)'!FQ80),\"\"))","v":""},{"$f":"'求人票(表)'!HB29","v":0},null,{"$f":"IF(ISBLANK('求人票(表)'!BQ7),\"\",IF(ISNUMBER('求人票(表)'!BQ7),'求人票(表)'!BQ7,IF(ISERROR(FIND(\".\",'求人票(表)'!BQ7)),DATE(_xlfn.NUMBERVALUE(LEFT('求人票(表)'!BQ7,FIND(\"．\",'求人票(表)'!BQ7)-1))+2018,INT(_xlfn.NUMBERVALUE(MID('求人票(表)'!BQ7,FIND(\"．\",'求人票(表)'!BQ7)+1,LEN('求人票(表)'!BQ7)-FIND(\"．\",'求人票(表)'!BQ7)))),RIGHT(MID('求人票(表)'!BQ7,FIND(\"．\",'求人票(表)'!BQ7)+1,LEN('求人票(表)'!BQ7)-FIND(\"．\",'求人票(表)'!BQ7)),LEN(MID('求人票(表)'!BQ7,FIND(\"．\",'求人票(表)'!BQ7)+1,LEN('求人票(表)'!BQ7)-FIND(\"．\",'求人票(表)'!BQ7)))-FIND(\"．\",MID('求人票(表)'!BQ7,FIND(\"．\",'求人票(表)'!BQ7)+1,LEN('求人票(表)'!BQ7)-FIND(\"．\",'求人票(表)'!BQ7))))),DATE(_xlfn.NUMBERVALUE(LEFT('求人票(表)'!BQ7,FIND(\".\",'求人票(表)'!BQ7)-1))+2018,INT(_xlfn.NUMBERVALUE(MID('求人票(表)'!BQ7,FIND(\".\",'求人票(表)'!BQ7)+1,LEN('求人票(表)'!BQ7)-FIND(\".\",'求人票(表)'!BQ7)))),RIGHT(MID('求人票(表)'!BQ7,FIND(\".\",'求人票(表)'!BQ7)+1,LEN('求人票(表)'!BQ7)-FIND(\".\",'求人票(表)'!BQ7)),LEN(MID('求人票(表)'!BQ7,FIND(\".\",'求人票(表)'!BQ7)+1,LEN('求人票(表)'!BQ7)-FIND(\".\",'求人票(表)'!BQ7)))-FIND(\".\",MID('求人票(表)'!BQ7,FIND(\".\",'求人票(表)'!BQ7)+1,LEN('求人票(表)'!BQ7)-FIND(\".\",'求人票(表)'!BQ7))))))))","v":""},{"$f":"IF('求人票(表)'!W38=\"■\",'求人票(表)'!Z37,IF('求人票(表)'!AH38=\"■\",IF('求人票(表)'!AZ38=\"\",'求人票(表)'!AK37,'求人票(表)'!AZ38),\"\"))","v":""},{"$f":"IF(OR(LEFT('求人票(表)'!HE96,1)=\"〇\",LEFT('求人票(表)'!HE96,1)=\"△\",LEFT('求人票(表)'!HE96,1)=\"◇\",LEFT('求人票(表)'!HE96,1)=\"□\"),LEFT('求人票(表)'!HE96,1),IF(OR(LEFT('求人票(表)'!HL96,1)=\"〇\",LEFT('求人票(表)'!HL96,1)=\"△\",LEFT('求人票(表)'!HL96,1)=\"◇\",LEFT('求人票(表)'!HL96,1)=\"□\"),LEFT('求人票(表)'!HL96,1),IF(ISBLANK('求人票(表)'!HS96),\"\",LEFT('求人票(表)'!HS96,1))))","v":""},{"$f":"IF('求人票(表)'!CQ102=\"■\",\"〇\",\"\")","v":""},{"$f":"IF('求人票(表)'!DP102=\"■\",\"〇\",\"\")","v":""},{"$nulls":7},{"$f":"IF('求人票(表)'!K6=\"■\",IF('求人票(表)'!K9=\"■\",\"区分なし\",LEFT('求人票(表)'!N5,1)),IF('求人票(表)'!K9=\"■\",LEFT('求人票(表)'!N8,1),\"\"))","v":""}]
[]
[]
[397,"仙台",1,"2023-06-05",6,"１四","株式会社　ウエルシスパートナーズ","うえるしすぱーとなーず","宮城県","仙台市青葉区一番町１丁目１－３０　南町通有楽館ビル５Ｆ","栗原市、遠田郡美里町、仙台市太白区、亘理郡亘理町",60,null,3000,"〇","訪問介護",1,"","普通自動車免許・介護職員初任者研修修了必須ワード・エクセル基本操作必須","","新","０７００～２２００","その他","完全","月給制",{"v":143000,"d":"¥143,000"},{"v":165000,"d":"¥165,000"},{"v":168000,"d":"¥168,000"},{"v":210000,"d":"¥210,000"},{"v":0,"d":"¥0"},{"v":0,"d":"¥0"},{"v":0,"d":"¥0"},"実費(最高26400円まで)","職務5000～20000、資格5000～10000、処遇改善15000","年2回  年1月分 ","無",70,73,"丸山非常勤",null,"2024-03-31","正社員","","","","T-994","P85","051","Ｐ　医療・福祉業","Ｇ ： サービス業","8-51：福祉介護の職業","Ｈ：その他","区分なし"]
[461,"仙台",1,"2023-07-06",7,"２四","エム・ユー・トラスト総合管理　株式会社","えむ・ゆー・とらすとそうごうかんり","東京都","港区北青山１丁目５－４　三菱UFJ信託銀行新青山ビル３Ｆ","仙台市青葉区",300,null,5000,"","サービス・スタッフ（銀行庶務員）",1,"","不問","","新10","０８５０～１７１０","土日祝その他","完全","月給制",{"v":225632,"d":"¥225,632"},{"v":225632,"d":"¥225,632"},{"v":225632,"d":"¥225,632"},{"v":225632,"d":"¥225,632"},{"v":0,"d":"¥0"},{"v":0,"d":"¥0"},{"v":0,"d":"¥0"},"実費(最高上限なし円まで)","無","年2回  年4月分 ","1","60","65","丸山非常勤",null,"2024-03-31","嘱託","","","〇","T-1271","R91","034","Ｒ　サービス業（他に分類されないもの）","Ｇ ： サービス業","6-34：事務的職業","Ｂ：事務・会計","定"]
[122,"仙台",1,"2023-04-21",4,"１四","株式会社　エイジェック　仙台オフィス","えいじぇっく　せんだいおふぃす","宮城県","仙台市青葉区中央１丁目３－１　AERビル１７階","宮城県内",18100,null,1000,"〇","ファクトリーサポート職",30,"","普通自動車免許必須","〇","新","0900～1800、交代制","土日祝その他","完全","月給制",{"v":172000,"d":"¥172,000"},{"v":176000,"d":"¥176,000"},{"v":202000,"d":"¥202,000"},{"v":206000,"d":"¥206,000"},{"v":0,"d":"¥0"},{"v":0,"d":"¥0"},{"v":0,"d":"¥0"},"実費(最高15000円まで)","識能30000、住宅、資格取得奨励金","年2回",3,65,70,"丸山非常勤",null,"2024-03-31","正社員","□","","〇","N-300","R91","073","Ｒ　サービス業（他に分類されないもの）","Ｇ ： サービス業","12-73：製造修理塗装製図等の職業","Ｅ：生産・工員","任"]
[]
[]
[]
[]
[{"$nulls":21},{"$f":"'求人票(表)'!CZ27","v":0}]